{"id":1929,"date":"2023-12-14T10:00:35","date_gmt":"2023-12-14T10:00:35","guid":{"rendered":"https:\/\/imperia.com\/product\/la-fabbrica-della-pasta\/"},"modified":"2026-03-22T15:37:14","modified_gmt":"2026-03-22T14:37:14","slug":"la-fabbrica-della-pasta","status":"publish","type":"product","link":"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/","title":{"rendered":"La Fabbrica della Pasta"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>LaFabbricaDellaPasta \u00e8 il set perfetto, progettato per soddisfare una vasta gamma di esigenze nella preparazione della pasta, consente di realizzare sfoglie di pasta, spaghetti, tagliatelle, fettuccine, lasagnette, ravioli e gnocchetti.<\/p>\n<p><strong>Caratteristiche Principali:<\/strong><\/p>\n<ul>\n<li>Ingegneria made in Italy: Realizzato con precisione per durabilit\u00e0 e longevit\u00e0.<\/li>\n<li>Opzioni di Pasta Versatili: include Raviolamp formato 34x34mm e accessorio Millegnocchi.<\/li>\n<li>Qualit\u00e0 Professionale.\n<div class=\"section\">\n<div class=\"layoutArea\"><\/div>\n<\/div>\n<\/li>\n<\/ul>\n","protected":false},"featured_media":1845,"template":"","meta":[],"product_brand":[],"product_cat":[81,82,83,84,72,86,89,90,91],"product_tag":[],"class_list":{"0":"post-1929","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cavatelli-it","7":"product_cat-fettuccine-65-mm-it","8":"product_cat-gnocchetti-sardi-it","9":"product_cat-lasagnette-12-mm-it","10":"product_cat-linea-classica-it","11":"product_cat-ravioli-it","12":"product_cat-rigatelli-it","13":"product_cat-spaghetti-2-mm-it","14":"product_cat-tagliolini-2-mm-it","16":"first","17":"instock","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Fabbrica della Pasta | Imperia Pasta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Fabbrica della Pasta | Imperia Pasta\" \/>\n<meta property=\"og:description\" content=\"LaFabbricaDellaPasta \u00e8 il set perfetto, progettato per soddisfare una vasta gamma di esigenze nella preparazione della pasta, consente di realizzare sfoglie di pasta, spaghetti, tagliatelle, fettuccine, lasagnette, ravioli e gnocchetti.  Caratteristiche Principali:   Ingegneria made in Italy: Realizzato con precisione per durabilit\u00e0 e longevit\u00e0.  Opzioni di Pasta Versatili: include Raviolamp formato 34x34mm e accessorio Millegnocchi.  Qualit\u00e0 Professionale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/\" \/>\n<meta property=\"og:site_name\" content=\"Imperia Pasta\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/imperiapasta\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-22T14:37:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/imperia.com\/wp-content\/uploads\/2023\/12\/fabbrica-pasta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/\",\"url\":\"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/\",\"name\":\"La Fabbrica della Pasta | Imperia Pasta\",\"isPartOf\":{\"@id\":\"https:\/\/imperia.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/imperia.com\/wp-content\/uploads\/2023\/12\/fabbrica-pasta.jpg\",\"datePublished\":\"2023-12-14T10:00:35+00:00\",\"dateModified\":\"2026-03-22T14:37:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/#primaryimage\",\"url\":\"https:\/\/imperia.com\/wp-content\/uploads\/2023\/12\/fabbrica-pasta.jpg\",\"contentUrl\":\"https:\/\/imperia.com\/wp-content\/uploads\/2023\/12\/fabbrica-pasta.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/imperia.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/imperia.com\/it\/negozio-old\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La Fabbrica della Pasta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/imperia.com\/#website\",\"url\":\"https:\/\/imperia.com\/\",\"name\":\"Imperia Pasta Machines\",\"description\":\"Progressive Italian Pasta Machines since 1932\",\"publisher\":{\"@id\":\"https:\/\/imperia.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/imperia.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/imperia.com\/#organization\",\"name\":\"Imperia Pasta\",\"url\":\"https:\/\/imperia.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/imperia.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/imperia.com\/wp-content\/uploads\/2023\/07\/cropped-logo.png\",\"contentUrl\":\"https:\/\/imperia.com\/wp-content\/uploads\/2023\/07\/cropped-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Imperia Pasta\"},\"image\":{\"@id\":\"https:\/\/imperia.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/imperiapasta\",\"https:\/\/www.instagram.com\/imperiapasta\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Fabbrica della Pasta | Imperia Pasta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/","og_locale":"it_IT","og_type":"article","og_title":"La Fabbrica della Pasta | Imperia Pasta","og_description":"LaFabbricaDellaPasta \u00e8 il set perfetto, progettato per soddisfare una vasta gamma di esigenze nella preparazione della pasta, consente di realizzare sfoglie di pasta, spaghetti, tagliatelle, fettuccine, lasagnette, ravioli e gnocchetti.  Caratteristiche Principali:   Ingegneria made in Italy: Realizzato con precisione per durabilit\u00e0 e longevit\u00e0.  Opzioni di Pasta Versatili: include Raviolamp formato 34x34mm e accessorio Millegnocchi.  Qualit\u00e0 Professionale.","og_url":"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/","og_site_name":"Imperia Pasta","article_publisher":"https:\/\/www.facebook.com\/imperiapasta","article_modified_time":"2026-03-22T14:37:14+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/imperia.com\/wp-content\/uploads\/2023\/12\/fabbrica-pasta.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/","url":"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/","name":"La Fabbrica della Pasta | Imperia Pasta","isPartOf":{"@id":"https:\/\/imperia.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/#primaryimage"},"image":{"@id":"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/#primaryimage"},"thumbnailUrl":"https:\/\/imperia.com\/wp-content\/uploads\/2023\/12\/fabbrica-pasta.jpg","datePublished":"2023-12-14T10:00:35+00:00","dateModified":"2026-03-22T14:37:14+00:00","breadcrumb":{"@id":"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/#primaryimage","url":"https:\/\/imperia.com\/wp-content\/uploads\/2023\/12\/fabbrica-pasta.jpg","contentUrl":"https:\/\/imperia.com\/wp-content\/uploads\/2023\/12\/fabbrica-pasta.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/imperia.com\/it\/prodotto\/la-fabbrica-della-pasta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/imperia.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/imperia.com\/it\/negozio-old\/"},{"@type":"ListItem","position":3,"name":"La Fabbrica della Pasta"}]},{"@type":"WebSite","@id":"https:\/\/imperia.com\/#website","url":"https:\/\/imperia.com\/","name":"Imperia Pasta Machines","description":"Progressive Italian Pasta Machines since 1932","publisher":{"@id":"https:\/\/imperia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/imperia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/imperia.com\/#organization","name":"Imperia Pasta","url":"https:\/\/imperia.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/imperia.com\/#\/schema\/logo\/image\/","url":"https:\/\/imperia.com\/wp-content\/uploads\/2023\/07\/cropped-logo.png","contentUrl":"https:\/\/imperia.com\/wp-content\/uploads\/2023\/07\/cropped-logo.png","width":512,"height":512,"caption":"Imperia Pasta"},"image":{"@id":"https:\/\/imperia.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/imperiapasta","https:\/\/www.instagram.com\/imperiapasta\/"]}]}},"_links":{"self":[{"href":"https:\/\/imperia.com\/it\/wp-json\/wp\/v2\/product\/1929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imperia.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/imperia.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imperia.com\/it\/wp-json\/wp\/v2\/media\/1845"}],"wp:attachment":[{"href":"https:\/\/imperia.com\/it\/wp-json\/wp\/v2\/media?parent=1929"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/imperia.com\/it\/wp-json\/wp\/v2\/product_brand?post=1929"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/imperia.com\/it\/wp-json\/wp\/v2\/product_cat?post=1929"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/imperia.com\/it\/wp-json\/wp\/v2\/product_tag?post=1929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}